{"id":47,"date":"2024-05-20T12:59:25","date_gmt":"2024-05-20T10:59:25","guid":{"rendered":"https:\/\/ddc.cmshulp.nl\/?page_id=47"},"modified":"2024-07-05T15:57:33","modified_gmt":"2024-07-05T13:57:33","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/www.dutchdiecasttrading.com\/it\/privacy-policy\/","title":{"rendered":"Politica sulla riservatezza"},"content":{"rendered":"<p>Dutch Diecast Trading, con sede a Flessingsterrein 20,<br>9665BZ Oude Pekela, \u00e8 responsabile del trattamento dei dati personali come indicato nella presente informativa sulla privacy.<\/p>\n\n\n\n<p>Dettagli del contatto:<br>https:\/\/www.dutchdiecasttrading.com<br>Flessingsterrein 20,<br>9665BZ Oude Pekela<br>Sig. S.dijkstra \u00e8 il responsabile della protezione dei dati di Dutch Diecast Trading. Pu\u00f2 essere contattato tramite info@dutchdiecasttrading.com<\/p>\n\n\n\n<p><br>Dutch Diecast Trading tratta i tuoi dati personali perch\u00e9 utilizzi i nostri servizi e\/o perch\u00e9 ce li fornisci tu stesso.<\/p>\n\n\n\n<p><em><strong>Di seguito troverai una panoramica dei dati personali che trattiamo:<\/strong><\/em>- Nome e cognome<br>- Dati indirizzo<br>- Numero di telefono<br>- Indirizzo e-mail<br>\u2013 Altri dati personali che fornisci attivamente, ad esempio creando un profilo su questo sito web, nella corrispondenza e per telefono<br>\u2013 Informazioni sulle vostre attivit\u00e0 sul nostro sito web<\/p>\n\n\n\n<p><em><strong>Dati personali particolari e\/o sensibili che trattiamo:<\/strong><\/em><\/p>\n\n\n\n<p><br>Il nostro sito Web e\/o servizio non intende raccogliere dati sui visitatori del sito Web di et\u00e0 inferiore a 16 anni. A meno che non abbiano il permesso dei genitori o dei tutori. Tuttavia, non possiamo verificare se un visitatore ha pi\u00f9 di 16 anni. Raccomandiamo pertanto che i genitori siano coinvolti nelle attivit\u00e0 online dei propri figli per evitare che i dati sui bambini vengano raccolti senza il consenso dei genitori. Se sei convinto che abbiamo raccolto informazioni personali su un minore senza questo consenso, contattaci all'indirizzo info@dutchdiecasttrading.com e cancelleremo queste informazioni.<\/p>\n\n\n\n<p><br><em><strong>Per quale scopo e su quale base trattiamo i dati personali:<\/strong><\/em><\/p>\n\n\n\n<p><br>Dutch Diecast Trading tratta i tuoi dati personali per i seguenti scopi:<br>\u2013 Gestire il pagamento<br>\u2013 Invio della nostra newsletter e\/o brochure pubblicitaria<br>\u2013 Per poterti chiamare o inviarti un\u2019e-mail se ci\u00f2 \u00e8 necessario per fornire i nostri servizi<br>\u2013 Per informarti sulle modifiche ai nostri servizi e prodotti<br>\u2013 Offrirti l\u2019opportunit\u00e0 di creare un account<br>\u2013 Per fornirti beni e servizi<br>\u2013 Dutch Diecast Trading tratta anche i dati personali se siamo legalmente obbligati a farlo, come i dati di cui abbiamo bisogno per la nostra dichiarazione dei redditi.<\/p>\n\n\n\n<p><br><em><strong>Per quanto tempo conserviamo i dati personali:<\/strong><\/em><\/p>\n\n\n\n<p>Dutch Diecast Trading non conserva i tuoi dati personali per un periodo pi\u00f9 lungo di quello strettamente necessario a raggiungere gli scopi per i quali sono raccolti. Utilizziamo i seguenti periodi di conservazione per tutti i dati personali: 10 anni.<\/p>\n\n\n\n<p><br><em><strong>Condivisione dei dati personali con terze parti:<\/strong><\/em><\/p>\n\n\n\n<p><br>Dutch Diecast Trading fornisce dati solo a terzi e solo se ci\u00f2 \u00e8 necessario per l'esecuzione del nostro accordo con voi o per rispettare un obbligo legale.<\/p>\n\n\n\n<p><br><em><strong>Cookie, o tecniche simili, che utilizziamo:<\/strong><\/em><\/p>\n\n\n\n<p><br>Dutch Diecast Trading utilizza cookie funzionali, analitici e di tracciamento. Un cookie \u00e8 un piccolo file di testo che viene memorizzato nel browser del tuo computer, tablet o smartphone quando visiti per la prima volta questo sito web. DutchDiecastTrading utilizza cookie con funzionalit\u00e0 puramente tecniche. Questi garantiscono che il sito web funzioni correttamente e che, ad esempio, le vostre impostazioni sulle preferenze vengano ricordate. Questi cookie vengono utilizzati anche per garantire il corretto funzionamento del sito web e per ottimizzarlo. Inseriamo inoltre cookie che tracciano il tuo comportamento di navigazione in modo da poter offrire contenuti e pubblicit\u00e0 personalizzati.<\/p>\n\n\n\n<p>Alla tua prima visita al nostro sito web, ti abbiamo gi\u00e0 informato di questi cookie e ti abbiamo chiesto il permesso di inserirli.<\/p>\n\n\n\n<p>Puoi annullare l'iscrizione ai cookie impostando il tuo browser Internet in modo che non memorizzi pi\u00f9 i cookie. Inoltre potete anche cancellare tutte le informazioni precedentemente memorizzate tramite le impostazioni del vostro browser.<\/p>\n\n\n\n<p>Zie voor een toelichting: https:\/\/veiliginternetten.nl\/themes\/situatie\/cookies-wat-zijn-het-en-wat-doe-ik-ermee\/<\/p>\n\n\n\n<p><br><em><strong>Visualizza, modifica o elimina i dati:<\/strong><\/em><\/p>\n\n\n\n<p><br>Hai il diritto di visualizzare, correggere o cancellare i tuoi dati personali. Inoltre, hai il diritto di revocare il tuo consenso al trattamento dei dati o di opporti al trattamento dei tuoi dati personali da parte di Dutch Diecast Trading e hai il diritto alla portabilit\u00e0 dei dati. Ci\u00f2 significa che puoi inviarci una richiesta per inviare i dati personali che abbiamo su di te in un file informatico a te o ad un'altra organizzazione da te menzionata.<\/p>\n\n\n\n<p>Puoi inviare una richiesta di accesso, correzione, cancellazione, trasferimento dei tuoi dati personali o richiesta di revoca del tuo consenso o opposizione al trattamento dei tuoi dati personali a info@dutchdiecasttrading.com.<\/p>\n\n\n\n<p>Per garantire che la richiesta di accesso sia stata effettuata da te, ti chiediamo di allegare alla richiesta una copia del tuo documento di identit\u00e0. Rendi neri la tua foto del passaporto, l'MRZ (zona a lettura ottica, la striscia con i numeri nella parte inferiore del passaporto), il numero del passaporto e il numero di servizio del cittadino (BSN) in questa copia. Questo \u00e8 per proteggere la tua privacy. Risponderemo alla tua richiesta il pi\u00f9 rapidamente possibile, ma entro quattro settimane.<\/p>\n\n\n\n<p>Dutch Diecast Trading wil u er tevens op wijzen dat u de mogelijkheid heeft om een klacht in te dienen bij de nationale toezichthouder, de Autoriteit Persoonsgegevens. Dat kan via de volgende link: https:\/\/autoriteitpersoonsgegevens.nl\/nl\/contact-met-de-autoriteit-persoonsgegevens\/tip-ons<\/p>\n\n\n\n<p><em><strong>Come proteggiamo i dati personali:<\/strong><\/em><\/p>\n\n\n\n<p><br>Dutch Diecast Trading prende sul serio la protezione dei tuoi dati e adotta misure adeguate per prevenire usi impropri, perdite, accessi non autorizzati, divulgazione indesiderata e modifiche non autorizzate. Se hai l'impressione che i tuoi dati non siano adeguatamente protetti o che ci siano indizi di uso improprio, contatta il nostro servizio clienti o tramite info@DutchDiecastTrading.com<\/p>","protected":false},"excerpt":{"rendered":"<p>Dutch Diecast Trading, gevestigd aan Flessingsterrein 20,9665BZ Oude Pekela, is verantwoordelijk voor de verwerking van persoonsgegevens zoals weergegeven in deze privacyverklaring. Contactgegevens:https:\/\/www.dutchdiecasttrading.comFlessingsterrein 20,9665BZ Oude PekelaDhr. S.dijkstra is de Functionaris Gegevensbescherming van Dutch Diecast Trading Hij\/zij is te bereiken via info@dutchdiecasttrading.com Dutch Diecast Trading verwerkt uw persoonsgegevens doordat u gebruik maakt van onze diensten en\/of omdat [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_jf_save_progress":"","footnotes":""},"class_list":["post-47","page","type-page","status-publish","hentry"],"featured_image_src":null,"_links":{"self":[{"href":"https:\/\/www.dutchdiecasttrading.com\/it\/wp-json\/wp\/v2\/pages\/47","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dutchdiecasttrading.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dutchdiecasttrading.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dutchdiecasttrading.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dutchdiecasttrading.com\/it\/wp-json\/wp\/v2\/comments?post=47"}],"version-history":[{"count":13,"href":"https:\/\/www.dutchdiecasttrading.com\/it\/wp-json\/wp\/v2\/pages\/47\/revisions"}],"predecessor-version":[{"id":733,"href":"https:\/\/www.dutchdiecasttrading.com\/it\/wp-json\/wp\/v2\/pages\/47\/revisions\/733"}],"wp:attachment":[{"href":"https:\/\/www.dutchdiecasttrading.com\/it\/wp-json\/wp\/v2\/media?parent=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}